
{"id":8351,"date":"2024-09-12T10:04:49","date_gmt":"2024-09-12T08:04:49","guid":{"rendered":"http:\/\/krienko.test.iei-group.net\/informativa-sulla-privacy\/"},"modified":"2025-01-29T17:31:59","modified_gmt":"2025-01-29T16:31:59","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8351\" class=\"elementor elementor-8351 elementor-7322\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8af54e e-flex e-con-boxed e-con e-parent\" data-id=\"d8af54e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32a2f44 elementor-widget elementor-widget-spacer\" data-id=\"32a2f44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77015d1 elementor-widget elementor-widget-heading\" data-id=\"77015d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informativa sulla privacy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b932dea elementor-widget elementor-widget-spacer\" data-id=\"b932dea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-224b2c27 e-flex e-con-boxed e-con e-parent\" data-id=\"224b2c27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20ed752d elementor-widget elementor-widget-text-editor\" data-id=\"20ed752d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Krienko rispetta la tua privacy<\/strong>\n<strong>Leggi la politica<\/strong>\n<ol>\n \t<li><strong>CHI \u00c8 IL TITOLARE DEL TRATTAMENTO DEI TUOI DATI PERSONALI?<\/strong>\nKrienko (&#8220;Krienko&#8221;), con sede legale in via &#8220;Llukan Toska&#8221;, FIER, ALBANIA, in persona del legale rappresentante Sig. Krienko Memo, indirizzo e-mail <a rel=\"noopener\">info@krienko.com,<\/a> \u00e8 il &#8220;Titolare del trattamento&#8221;.<\/li>\n \t<li><strong>QUAL \u00c8 IL TIPO DI DATI CHE KRIENKO ELABORA?<\/strong>\nIl Titolare tratta i dati personali degli utenti dei suoi servizi di comunicazione elettronica, che includono nome, cognome, indirizzo, numero di telefono, numero di cellulare, indirizzo e-mail e qualsiasi tipo di dato di contatto (&#8220;Dati Personali&#8221;). Il Titolare del Trattamento potr\u00e0 inoltre trattare i tuoi dati personali sensibili, con specifico ed esclusivo riferimento ai tuoi dati medici, biometrici o genetici (&#8220;Dati Personali relativi alla Salute&#8221;).\n<\/li>\n \t<li><strong>INFORMAZIONI SUL TRATTAMENTO DEI DATI<\/strong>\nIl Titolare tratta i Dati Personali forniti dagli utenti nella forma appropriata per offrire un servizio di qualit\u00e0 ai propri clienti e per rispondere meglio alle loro richieste. Questi dati danno a Krienko la possibilit\u00e0 di migliorare ulteriormente i propri servizi e di fornire informazioni in base alle richieste degli utenti, ad esempio tramite SMS, MMS, e-mail, telemarketing, ecc. <\/li>\n<\/ol>\n<ul>\n \t<li>I dati personali che Krienko raccoglie dai suoi clienti sono sempre utilizzati in conformit\u00e0 alla legislazione vigente.<\/li>\n \t<li>I dati personali sono trattati in modo onesto, corretto e nel rispetto della legge.<\/li>\n \t<li>I dati personali sono trattati solo per il periodo di tempo pertinente agli obiettivi specifici per i quali vengono raccolti da Krienko.<\/li>\n \t<li>Tutti i metodi di raccolta dei dati personali (ad esempio i moduli di richiesta clienti) prevedono un&#8217;informazione completa e chiara sul motivo della raccolta, anche se potrebbe essere di natura secondaria e non facilmente comprensibile (ad esempio, se i dati personali vengono raccolti per scopi di marketing, ti verr\u00e0 spiegato e ti verr\u00e0 data la possibilit\u00e0 di rifiutare di fornire i dati).<\/li>\n<\/ul>\n<strong>Focus sul trattamento dei dati personali relativi alla salute<\/strong>\nIl Titolare del trattamento tratter\u00e0 i dati personali relativi alla salute dell&#8217;utente solo se necessario per l&#8217;esecuzione del servizio specifico richiesto dall&#8217;utente a Krienko.\nIl consenso esplicito \u00e8 sempre richiesto per il trattamento dei dati personali relativi alla salute degli utenti.\nAd esempio, il Titolare del trattamento pu\u00f2 chiedere il consenso esplicito quando un servizio specifico richiesto dall&#8217;utente comporta la trasmissione e\/o il confronto di preventivi di procedure odontoiatriche.\nIn questi casi, Krienko pu\u00f2 richiedere all&#8217;utente di allegare alcuni documenti medici o odontoiatrici alla richiesta specifica. <strong>Focus sulla distribuzione dei dati personali a terzi<\/strong>\nLa distribuzione dei dati personali a terzi \u00e8 consentita solo se questi soggetti sono agenti di Krienko o al suo servizio, e se agiscono in conformit\u00e0 alle nostre istruzioni. Krienko non trasmette i tuoi dati personali a terzi, a meno che tu non abbia dato il tuo esplicito consenso. Se l&#8217;utente ha dato il consenso a una terza parte per la ricezione dei dati da parte di Krienko, Krienko non \u00e8 responsabile della fornitura o del trasferimento di tali dati.\n\n  \n<ol start=\"4\">\n \t<li><strong>COME PUOI ACCEDERE AI TUOI DATI<\/strong>\nAi sensi della legge n. 9887 del 10.03.2008 &#8220;sulla protezione dei dati personali&#8221;, hai il diritto di richiedere informazioni sui tuoi dati personali trattati dal Titolare del trattamento e ti risponderemo entro 30 giorni. La richiesta deve essere inviata per iscritto al seguente indirizzo: <a rel=\"noopener\">info@krienko.com.<\/a>\nNella richiesta devi indicare il tuo nome, indirizzo e numero di cellulare. Krienko adotter\u00e0 tutte le misure necessarie per verificare la tua identit\u00e0 prima di rilasciare una copia delle informazioni.  <\/li>\n \t<li><strong>PER QUANTO TEMPO I DATI PERSONALI DELL&#8217;UTENTE SARANNO CONSERVATI DA NOI?<\/strong>\n<strong>Focus sulla conservazione dei dati<\/strong>\nI dati personali saranno conservati per il tempo necessario in conformit\u00e0 con lo scopo principale per cui sono stati raccolti.\nIl periodo di conservazione dei dati sar\u00e0 pienamente conforme al quadro giuridico vigente.\nIn alcuni casi, alcuni dati che normalmente non verrebbero conservati da Krienko potrebbero essere salvati a causa di circostanze particolari, come ad esempio indagini giudiziarie.<\/li>\n<\/ol>\nIl periodo di conservazione dei dati \u00e8 il seguente:\n<ul>\n \t<li>I dati provenienti dai moduli di contatto con i clienti vengono conservati per il tempo necessario a garantire la fornitura dei servizi. I dati sul traffico sono conservati per essere utilizzati dalla procura e dai tribunali nei casi penali, in conformit\u00e0 con la legislazione vigente. <\/li>\n \t<li>Conserveremo i dati personali dell&#8217;utente solo per il tempo necessario.<\/li>\n<\/ul>\nI dati personali vengono cancellati dopo un tempo ragionevole in base ai seguenti criteri di conservazione:\n<ul>\n \t<li>Conserviamo i tuoi dati finch\u00e9 abbiamo un rapporto continuativo con te (in particolare, se hai un account con noi).<\/li>\n \t<li>Conserveremo i dati solo finch\u00e9 il tuo account sar\u00e0 attivo o per il tempo necessario a fornirti i servizi.<\/li>\n \t<li>Conserviamo i tuoi dati per il tempo necessario a rispettare i nostri obblighi legali e contrattuali globali.<\/li>\n \t<li>Conserviamo i tuoi Dati personali relativi alla salute per un massimo di 30 giorni.<\/li>\n<\/ul>\n<ol start=\"6\">\n \t<li><strong>INFORMAZIONI SULLA CORREZIONE E LA CANCELLAZIONE DEI DATI PERSONALI<\/strong>\nPer la correzione o la cancellazione dei tuoi dati personali, ti preghiamo di contattarci per iscritto al seguente indirizzo: <a rel=\"noopener\">info@krienko.com.<\/a> Krienko, in conformit\u00e0 con la legge n. 9887 del 10.03.2008 &#8220;sulla protezione dei dati personali&#8221;, \u00e8 legalmente obbligata a prendere provvedimenti per correggere o cancellare i tuoi dati personali entro 30 giorni. La richiesta scritta pu\u00f2 essere accompagnata da una copia di un documento d&#8217;identit\u00e0 valido.  <\/li>\n \t<li><strong>MISURE DI SICUREZZA PER I DATI PERSONALI<\/strong>\nKrienko \u00e8 consapevole dell&#8217;importanza e della delicatezza dei dati personali e si attiene rigorosamente alle misure di sicurezza previste dalla Legge n. 9887 del 10.03.2008 &#8220;sulla protezione dei dati personali&#8221;. Ci\u00f2 avviene attraverso l&#8217;utilizzo di tecniche avanzate e moderne per la conservazione dei database e dei sistemi informatici. Inoltre, Krienko garantisce che i trasferimenti e le registrazioni dei dati avvengano nel rispetto di rigorose misure di sicurezza, in piena conformit\u00e0 con la legislazione in materia.  <\/li>\n<\/ol>\nTuttavia, il sito di Krienko pu\u00f2 contenere link ad altri siti web. Krienko non \u00e8 responsabile del contenuto di tali siti e ti consiglia di leggere le dichiarazioni sulla privacy di tali siti. Le condizioni di tali siti possono differire da quelle di Krienko.  \n<ol start=\"8\">\n \t<li><strong>HAI DOMANDE O SUGGERIMENTI? NON ESITARE A CONTATTARCI! <\/strong>\nCon le spiegazioni di cui sopra, Krienko spera di averti fornito informazioni complete e accurate sulle sue politiche sulla privacy relative ai servizi che fornisce.\nSe hai domande, reclami\/richieste o suggerimenti, contattaci all&#8217;indirizzo: <a rel=\"noopener\">info@krienko.com.<\/a><\/li>\n \t<li><strong>VARIE<\/strong>\nIl presente regolamento deve essere interpretato in conformit\u00e0 alle Condizioni Generali di questo sito e alle Condizioni Generali applicate da Krienko ai propri clienti.\nKrienko si riserva il diritto di cambiare o modificare il presente regolamento in qualsiasi momento, in linea con eventuali cambiamenti nella legislazione sulla protezione dei dati personali e sulla privacy.<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informativa sulla privacy Krienko rispetta la tua privacy Leggi la politica CHI \u00c8 IL TITOLARE DEL TRATTAMENTO DEI TUOI DATI PERSONALI? Krienko (&#8220;Krienko&#8221;), con sede legale in via &#8220;Llukan Toska&#8221;, FIER, ALBANIA, in persona del legale rappresentante Sig. Krienko Memo, indirizzo e-mail info@krienko.com, \u00e8 il &#8220;Titolare del trattamento&#8221;. QUAL \u00c8 IL TIPO DI DATI CHE [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-8351","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativa sulla privacy - Krienko Jeans<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sulla privacy\" \/>\n<meta property=\"og:description\" content=\"Informativa sulla privacy Krienko rispetta la tua privacy Leggi la politica CHI \u00c8 IL TITOLARE DEL TRATTAMENTO DEI TUOI DATI PERSONALI? Krienko (&#8220;Krienko&#8221;), con sede legale in via &#8220;Llukan Toska&#8221;, FIER, ALBANIA, in persona del legale rappresentante Sig. Krienko Memo, indirizzo e-mail info@krienko.com, \u00e8 il &#8220;Titolare del trattamento&#8221;. QUAL \u00c8 IL TIPO DI DATI CHE [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Krienko Jeans\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T16:31:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/krienko.com\\\/it\\\/informativa-sulla-privacy\\\/\",\"url\":\"https:\\\/\\\/krienko.com\\\/it\\\/informativa-sulla-privacy\\\/\",\"name\":\"Informativa sulla privacy - Krienko Jeans\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krienko.com\\\/it\\\/#website\"},\"datePublished\":\"2024-09-12T08:04:49+00:00\",\"dateModified\":\"2025-01-29T16:31:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/krienko.com\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/krienko.com\\\/it\\\/informativa-sulla-privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/krienko.com\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/krienko.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativa sulla privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/krienko.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/krienko.com\\\/it\\\/\",\"name\":\"krienko\",\"description\":\"KRIENKO Outlet Expansion FOR GLOBAL FASHION. N\u00eb vitin 2025, KRIENKO do t\u00eb festoj\u00eb p\u00ebrfundimin e nj\u00eb prej projekteve t\u00eb saj m\u00eb t\u00eb m\u00ebdha deri m\u00eb tani: nj\u00eb ...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/krienko.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy - Krienko Jeans","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Informativa sulla privacy","og_description":"Informativa sulla privacy Krienko rispetta la tua privacy Leggi la politica CHI \u00c8 IL TITOLARE DEL TRATTAMENTO DEI TUOI DATI PERSONALI? Krienko (&#8220;Krienko&#8221;), con sede legale in via &#8220;Llukan Toska&#8221;, FIER, ALBANIA, in persona del legale rappresentante Sig. Krienko Memo, indirizzo e-mail info@krienko.com, \u00e8 il &#8220;Titolare del trattamento&#8221;. QUAL \u00c8 IL TIPO DI DATI CHE [&hellip;]","og_url":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/","og_site_name":"Krienko Jeans","article_modified_time":"2025-01-29T16:31:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/","url":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/","name":"Informativa sulla privacy - Krienko Jeans","isPartOf":{"@id":"https:\/\/krienko.com\/it\/#website"},"datePublished":"2024-09-12T08:04:49+00:00","dateModified":"2025-01-29T16:31:59+00:00","breadcrumb":{"@id":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/krienko.com\/it\/informativa-sulla-privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/krienko.com\/it\/informativa-sulla-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/krienko.com\/it\/"},{"@type":"ListItem","position":2,"name":"Informativa sulla privacy"}]},{"@type":"WebSite","@id":"https:\/\/krienko.com\/it\/#website","url":"https:\/\/krienko.com\/it\/","name":"krienko","description":"KRIENKO Outlet Expansion FOR GLOBAL FASHION. N\u00eb vitin 2025, KRIENKO do t\u00eb festoj\u00eb p\u00ebrfundimin e nj\u00eb prej projekteve t\u00eb saj m\u00eb t\u00eb m\u00ebdha deri m\u00eb tani: nj\u00eb ...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/krienko.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/pages\/8351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/comments?post=8351"}],"version-history":[{"count":2,"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/pages\/8351\/revisions"}],"predecessor-version":[{"id":12983,"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/pages\/8351\/revisions\/12983"}],"wp:attachment":[{"href":"https:\/\/krienko.com\/it\/wp-json\/wp\/v2\/media?parent=8351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}